{"id":7480,"date":"2021-05-21T13:45:20","date_gmt":"2021-05-21T11:45:20","guid":{"rendered":"https:\/\/www.eltex.de\/?page_id=7480"},"modified":"2021-07-13T14:13:04","modified_gmt":"2021-07-13T12:13:04","slug":"eltex_mise_a_la_terre_electrostatique","status":"publish","type":"page","link":"https:\/\/www.eltex.de\/fr\/eltex_mise_a_la_terre_electrostatique\/","title":{"rendered":"ELTEX TERRALIGHT \u2013 MISE \u00c0 LA TERRE \u00c9LECTROSTATIQUE"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"tpl-redaktionelle-seite.php","meta":{"_acf_changed":false,"footnotes":""},"seitenfilter":[],"class_list":["post-7480","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ELTEX TERRALIGHT \u2013 MISE \u00c0 LA TERRE \u00c9LECTROSTATIQUE | Eltex Elektrostatik GmbH<\/title>\n<meta name=\"description\" content=\"Dem menschlichen Auge bleibt die Existenz statischer Elektrizit\u00e4t verborgen. Es erkennt sie erst, wenn sie sich entl\u00e4dt. Das \u00bbping\u00ab beim Griff an die T\u00fcre, die Papierschnipsel, die ein Bernstein beim Reiben anzieht, all das sind harmlose Beispiele des gleichen Ph\u00e4momens.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eltex.de\/fr\/eltex_mise_a_la_terre_electrostatique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ELTEX TERRALIGHT \u2013 MISE \u00c0 LA TERRE \u00c9LECTROSTATIQUE | Eltex Elektrostatik GmbH\" \/>\n<meta property=\"og:description\" content=\"Dem menschlichen Auge bleibt die Existenz statischer Elektrizit\u00e4t verborgen. Es erkennt sie erst, wenn sie sich entl\u00e4dt. Das \u00bbping\u00ab beim Griff an die T\u00fcre, die Papierschnipsel, die ein Bernstein beim Reiben anzieht, all das sind harmlose Beispiele des gleichen Ph\u00e4momens.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eltex.de\/fr\/eltex_mise_a_la_terre_electrostatique\/\" \/>\n<meta property=\"og:site_name\" content=\"Eltex Elektrostatik GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-13T12:13:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eltex.de\\\/fr\\\/eltex_mise_a_la_terre_electrostatique\\\/\",\"url\":\"https:\\\/\\\/www.eltex.de\\\/fr\\\/eltex_mise_a_la_terre_electrostatique\\\/\",\"name\":\"ELTEX TERRALIGHT \u2013 MISE \u00c0 LA TERRE \u00c9LECTROSTATIQUE | Eltex Elektrostatik GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eltex.de\\\/fr\\\/#website\"},\"datePublished\":\"2021-05-21T11:45:20+00:00\",\"dateModified\":\"2021-07-13T12:13:04+00:00\",\"description\":\"Dem menschlichen Auge bleibt die Existenz statischer Elektrizit\u00e4t verborgen. Es erkennt sie erst, wenn sie sich entl\u00e4dt. Das \u00bbping\u00ab beim Griff an die T\u00fcre, die Papierschnipsel, die ein Bernstein beim Reiben anzieht, all das sind harmlose Beispiele des gleichen Ph\u00e4momens.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eltex.de\\\/fr\\\/eltex_mise_a_la_terre_electrostatique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eltex.de\\\/fr\\\/eltex_mise_a_la_terre_electrostatique\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eltex.de\\\/fr\\\/eltex_mise_a_la_terre_electrostatique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Eltex\",\"item\":\"https:\\\/\\\/www.eltex.de\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ELTEX TERRALIGHT \u2013 MISE \u00c0 LA TERRE \u00c9LECTROSTATIQUE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eltex.de\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.eltex.de\\\/fr\\\/\",\"name\":\"Eltex Elektrostatik GmbH\",\"description\":\"Die Eltex Elektrostatik GmbH als moderner Partner der Industrie zur Steigerung von Produktivit\u00e4t, Effizienz und Ertragskraft in vielen Branchen.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eltex.de\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ELTEX TERRALIGHT \u2013 MISE \u00c0 LA TERRE \u00c9LECTROSTATIQUE | Eltex Elektrostatik GmbH","description":"Dem menschlichen Auge bleibt die Existenz statischer Elektrizit\u00e4t verborgen. Es erkennt sie erst, wenn sie sich entl\u00e4dt. Das \u00bbping\u00ab beim Griff an die T\u00fcre, die Papierschnipsel, die ein Bernstein beim Reiben anzieht, all das sind harmlose Beispiele des gleichen Ph\u00e4momens.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eltex.de\/fr\/eltex_mise_a_la_terre_electrostatique\/","og_locale":"fr_FR","og_type":"article","og_title":"ELTEX TERRALIGHT \u2013 MISE \u00c0 LA TERRE \u00c9LECTROSTATIQUE | Eltex Elektrostatik GmbH","og_description":"Dem menschlichen Auge bleibt die Existenz statischer Elektrizit\u00e4t verborgen. Es erkennt sie erst, wenn sie sich entl\u00e4dt. Das \u00bbping\u00ab beim Griff an die T\u00fcre, die Papierschnipsel, die ein Bernstein beim Reiben anzieht, all das sind harmlose Beispiele des gleichen Ph\u00e4momens.","og_url":"https:\/\/www.eltex.de\/fr\/eltex_mise_a_la_terre_electrostatique\/","og_site_name":"Eltex Elektrostatik GmbH","article_modified_time":"2021-07-13T12:13:04+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eltex.de\/fr\/eltex_mise_a_la_terre_electrostatique\/","url":"https:\/\/www.eltex.de\/fr\/eltex_mise_a_la_terre_electrostatique\/","name":"ELTEX TERRALIGHT \u2013 MISE \u00c0 LA TERRE \u00c9LECTROSTATIQUE | Eltex Elektrostatik GmbH","isPartOf":{"@id":"https:\/\/www.eltex.de\/fr\/#website"},"datePublished":"2021-05-21T11:45:20+00:00","dateModified":"2021-07-13T12:13:04+00:00","description":"Dem menschlichen Auge bleibt die Existenz statischer Elektrizit\u00e4t verborgen. Es erkennt sie erst, wenn sie sich entl\u00e4dt. Das \u00bbping\u00ab beim Griff an die T\u00fcre, die Papierschnipsel, die ein Bernstein beim Reiben anzieht, all das sind harmlose Beispiele des gleichen Ph\u00e4momens.","breadcrumb":{"@id":"https:\/\/www.eltex.de\/fr\/eltex_mise_a_la_terre_electrostatique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eltex.de\/fr\/eltex_mise_a_la_terre_electrostatique\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eltex.de\/fr\/eltex_mise_a_la_terre_electrostatique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Eltex","item":"https:\/\/www.eltex.de\/fr\/"},{"@type":"ListItem","position":2,"name":"ELTEX TERRALIGHT \u2013 MISE \u00c0 LA TERRE \u00c9LECTROSTATIQUE"}]},{"@type":"WebSite","@id":"https:\/\/www.eltex.de\/fr\/#website","url":"https:\/\/www.eltex.de\/fr\/","name":"Eltex Elektrostatik GmbH","description":"Die Eltex Elektrostatik GmbH als moderner Partner der Industrie zur Steigerung von Produktivit\u00e4t, Effizienz und Ertragskraft in vielen Branchen.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eltex.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.eltex.de\/fr\/wp-json\/wp\/v2\/pages\/7480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eltex.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.eltex.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.eltex.de\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eltex.de\/fr\/wp-json\/wp\/v2\/comments?post=7480"}],"version-history":[{"count":10,"href":"https:\/\/www.eltex.de\/fr\/wp-json\/wp\/v2\/pages\/7480\/revisions"}],"predecessor-version":[{"id":7676,"href":"https:\/\/www.eltex.de\/fr\/wp-json\/wp\/v2\/pages\/7480\/revisions\/7676"}],"wp:attachment":[{"href":"https:\/\/www.eltex.de\/fr\/wp-json\/wp\/v2\/media?parent=7480"}],"wp:term":[{"taxonomy":"seitenfilter","embeddable":true,"href":"https:\/\/www.eltex.de\/fr\/wp-json\/wp\/v2\/seitenfilter?post=7480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}